{"id":5323,"date":"2020-02-03T14:10:18","date_gmt":"2020-02-03T13:10:18","guid":{"rendered":"https:\/\/wolfpack-tires.de\/?p=5323"},"modified":"2020-03-17T12:24:04","modified_gmt":"2020-03-17T11:24:04","slug":"bronze-in-milton","status":"publish","type":"post","link":"https:\/\/wolfpack-tires.de\/en\/2020\/02\/03\/bronze-in-milton\/","title":{"rendered":"Bronze in Milton"},"content":{"rendered":"<p><strong>Bronze in Milton bei den Weltmeisterschaften im Paracycling<\/strong><\/p>\n<p>Kai Kruse und Robert F\u00f6rstemann haben bei den Weltmeisterschaften im Paracycling die Bronze-Medaille \u00fcber 1000m gewonnen. Nach ihrem Lauf \u00fcbernahmen das Team mit Bestzeit die F\u00fchrung. Es folgten weitere 6 Teams, damit war Spannung bis zum Schluss angesagt. Kai und Robert haben in diesem spannenden Wettkampf gezeigt, dass diese beiden Sportler als Team zur absoluten Weltspitze geh\u00f6ren. Neben den sportlichen Erfolgen zeigen die Beiden autentisch, dass Inklusion wirklich funktioniert und dass darin viel Spa\u00df und Freude steckt. Wir sind dankbar, dass wir als Unterst\u00fctzer an diesen Erfahrungen teilhaben d\u00fcrfen.<\/p>\n<div>Denise Schindler (im Bild) aus Cottbus in der Verfolgung der Klasse C3 und Maike Hausberger aus Trier in der Klasse C2 holten sich jeweils Bronze in Milton.<\/div>\n<div><\/div>\n<div>Unsere Weltmeisterschaftswochen sind im Februar 2020. Auf ausgew\u00e4hlte Artikel haben wir w\u00e4hrend der Weltmeisterschaften im Februar <a href=\"https:\/\/wolfpack-tires.de\/en\/weltmeisterschaftswochen\/\">attraktive Aktionspreise hier im Shop<\/a>.<\/div>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Bronze in Milton bei den Weltmeisterschaften im Paracycling Kai Kruse und Robert F\u00f6rstemann haben bei den Weltmeisterschaften im Paracycling die Bronze-Medaille \u00fcber 1000m gewonnen. Nach ihrem Lauf \u00fcbernahmen das Team mit Bestzeit die F\u00fchrung. Es folgten weitere 6 Teams, damit war Spannung bis zum Schluss angesagt. Kai und Robert haben in diesem spannenden Wettkampf gezeigt, [&hellip;]<\/p>","protected":false},"author":3,"featured_media":5324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":[],"categories":[1],"tags":[],"new_scheduled_revision":"","save_as_revision":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bronze in Milton - Deutschland erfolgreich im Tandem<\/title>\n<meta name=\"description\" content=\"Bronze in Milton - Deutschland erfolgreich im Tandem mit Kai Kruse und Robert F\u00f6rstemann bei den Weltmeisterschaften im Paracycling\" \/>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wolfpack-tires.de\/en\/weltmeisterschaftswochen\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bronze in Milton - Deutschland erfolgreich im Tandem\" \/>\n<meta property=\"og:description\" content=\"Bronze in Milton - Deutschland erfolgreich im Tandem mit Kai Kruse und Robert F\u00f6rstemann bei den Weltmeisterschaften im Paracycling\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wolfpack-tires.de\/en\/weltmeisterschaftswochen\/\" \/>\n<meta property=\"og:site_name\" content=\"Wolfpack - Angebote\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HeuerRadsport\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-03T13:10:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-17T11:24:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wolfpack-tires.de\/test\/wp-content\/uploads\/2020\/02\/MIlton-scaled-e1580995076641.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1369\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@radsport_heuer\" \/>\n<meta name=\"twitter:site\" content=\"@radsport_heuer\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/wolfpack-tires.de\/en\/#organization\",\"name\":\"Heuer Radsport\",\"url\":\"https:\/\/wolfpack-tires.de\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/HeuerRadsport\/\",\"https:\/\/www.instagram.com\/radsport_heuer\/\",\"https:\/\/www.youtube.com\/channel\/UCuFkVFhY376_zRGfw_0Oy-Q\",\"https:\/\/twitter.com\/radsport_heuer\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/wolfpack-tires.de\/en\/#logo\",\"inLanguage\":\"en-GB\",\"url\":\"https:\/\/wolfpack-tires.de\/test\/wp-content\/uploads\/2019\/01\/logo2.jpg\",\"width\":750,\"height\":186,\"caption\":\"Heuer Radsport\"},\"image\":{\"@id\":\"https:\/\/wolfpack-tires.de\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wolfpack-tires.de\/en\/#website\",\"url\":\"https:\/\/wolfpack-tires.de\/en\/\",\"name\":\"Heuer Radsport\",\"description\":\"Vollgas! oder einfach: Kette rechts\",\"publisher\":{\"@id\":\"https:\/\/wolfpack-tires.de\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/wolfpack-tires.de\/en\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/wolfpack-tires.de\/weltmeisterschaftswochen\/#primaryimage\",\"inLanguage\":\"en-GB\",\"url\":\"https:\/\/wolfpack-tires.de\/test\/wp-content\/uploads\/2020\/02\/MIlton-scaled-e1580995076641.jpeg\",\"width\":1920,\"height\":1369,\"caption\":\"Bronze in Milton\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wolfpack-tires.de\/weltmeisterschaftswochen\/#webpage\",\"url\":\"https:\/\/wolfpack-tires.de\/weltmeisterschaftswochen\/\",\"name\":\"Bronze in Milton - Deutschland erfolgreich im Tandem\",\"isPartOf\":{\"@id\":\"https:\/\/wolfpack-tires.de\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/wolfpack-tires.de\/weltmeisterschaftswochen\/#primaryimage\"},\"datePublished\":\"2020-02-03T13:10:18+00:00\",\"dateModified\":\"2020-03-17T11:24:04+00:00\",\"description\":\"Bronze in Milton - Deutschland erfolgreich im Tandem mit Kai Kruse und Robert F\\u00f6rstemann bei den Weltmeisterschaften im Paracycling\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wolfpack-tires.de\/weltmeisterschaftswochen\/\"]}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/wolfpack-tires.de\/weltmeisterschaftswochen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/wolfpack-tires.de\/weltmeisterschaftswochen\/#webpage\"},\"author\":{\"@id\":\"https:\/\/wolfpack-tires.de\/en\/#\/schema\/person\/f625bb5988ec93b90777a0374a855a12\"},\"headline\":\"Bronze in Milton\",\"datePublished\":\"2020-02-03T13:10:18+00:00\",\"dateModified\":\"2020-03-17T11:24:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/wolfpack-tires.de\/weltmeisterschaftswochen\/#webpage\"},\"publisher\":{\"@id\":\"https:\/\/wolfpack-tires.de\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/wolfpack-tires.de\/weltmeisterschaftswochen\/#primaryimage\"},\"articleSection\":\"Allgemein\",\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/wolfpack-tires.de\/en\/#\/schema\/person\/f625bb5988ec93b90777a0374a855a12\",\"name\":\"Joachim\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/wolfpack-tires.de\/en\/#personlogo\",\"inLanguage\":\"en-GB\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9f00a17b3cd01d9c027cab95a4746f9e?s=96&d=mm&r=g\",\"caption\":\"Joachim\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/wolfpack-tires.de\/en\/wp-json\/wp\/v2\/posts\/5323"}],"collection":[{"href":"https:\/\/wolfpack-tires.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wolfpack-tires.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wolfpack-tires.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wolfpack-tires.de\/en\/wp-json\/wp\/v2\/comments?post=5323"}],"version-history":[{"count":4,"href":"https:\/\/wolfpack-tires.de\/en\/wp-json\/wp\/v2\/posts\/5323\/revisions"}],"predecessor-version":[{"id":5528,"href":"https:\/\/wolfpack-tires.de\/en\/wp-json\/wp\/v2\/posts\/5323\/revisions\/5528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wolfpack-tires.de\/en\/wp-json\/wp\/v2\/media\/5324"}],"wp:attachment":[{"href":"https:\/\/wolfpack-tires.de\/en\/wp-json\/wp\/v2\/media?parent=5323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wolfpack-tires.de\/en\/wp-json\/wp\/v2\/categories?post=5323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wolfpack-tires.de\/en\/wp-json\/wp\/v2\/tags?post=5323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}